{"id":7594,"date":"2025-04-07T09:57:58","date_gmt":"2025-04-07T07:57:58","guid":{"rendered":"https:\/\/lzw.digi-sol.de\/?page_id=7594"},"modified":"2026-05-23T02:21:23","modified_gmt":"2026-05-23T00:21:23","slug":"icl-linsen","status":"publish","type":"page","link":"https:\/\/lzw-wiesbaden.de\/en\/linsenoperation\/icl-linsen\/","title":{"rendered":"ICL-Linsen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7594\" class=\"elementor elementor-7594\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-453fa29d e-flex e-con-boxed e-con e-parent\" data-id=\"453fa29d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6addcccb e-con-full e-flex e-con e-child\" data-id=\"6addcccb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-609783ec elementor-widget elementor-widget-heading\" data-id=\"609783ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ICL-Linsen ab 2.000\u20ac\/Auge<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29b10432 elementor-widget elementor-widget-heading\" data-id=\"29b10432\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Implantierbare Kontaktlinsen (ICL &amp; IPCL)<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b08257a elementor-widget elementor-widget-text-editor\" data-id=\"6b08257a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<article class=\"text-token-text-primary w-full\" dir=\"auto\" data-testid=\"conversation-turn-26\" data-scroll-anchor=\"true\"><div class=\"text-base my-auto mx-auto py-5 px-6\"><div class=\"mx-auto flex flex-1 text-base gap-4 md:gap-5 lg:gap-6 md:max-w-3xl group\/turn-messages focus-visible:outline-hidden\" tabindex=\"-1\"><div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn @xs\/thread:px-0 @sm\/thread:px-1.5 @md\/thread:px-4\"><div class=\"relative flex-col gap-1 md:gap-3\"><div class=\"flex max-w-full flex-col grow\"><div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"c24e2f17-39a3-4eea-ba42-a5b041a3b630\" data-message-model-slug=\"gpt-4o\"><div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\"><div class=\"markdown prose dark:prose-invert w-full break-words dark\"><p class=\"\" data-start=\"286\" data-end=\"511\">Die ICL-Linse ist besonders dann sinnvoll, wenn klassische Verfahren wie LASIK oder PRK nicht angewendet werden k\u00f6nnen \u2013 zum Beispiel bei hoher Fehlsichtigkeit, d\u00fcnner Hornhaut oder trockenen Augen.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe4cd79 e-con-full e-flex e-con e-child\" data-id=\"fe4cd79\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8482aa9 elementor-widget-tablet__width-auto elementor-widget__width-initial elementor-widget elementor-widget-shortcode\" data-id=\"8482aa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"drflex-button-wrapper\">\n        <a href=\"javascript:toggleDrFlexAppointments()\">\n            <div class=\"drflex-button drflex-button-secondary\"\n                style=\"border-radius: 1em;\n                    background-color: #68e697;\n                    color: #ffffff;\n                    padding: 1em;\">ICL-Linsen Eignungscheck (0\u20ac)\n            <\/div>\n        <\/a>\n    <\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a95915a elementor-widget-tablet__width-inherit elementor-widget-mobile__width-initial elementor-widget elementor-widget-button\" data-id=\"a95915a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:0611360220\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Termin vereinbaren: 0611-360 220<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2eb9ea2a e-flex e-con-boxed e-con e-parent\" data-id=\"2eb9ea2a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1a4dfc33 e-con-full e-flex e-con e-child\" data-id=\"1a4dfc33\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7b224445 e-flex e-con-boxed e-con e-child\" data-id=\"7b224445\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2a2f330e e-con-full e-flex e-con e-child\" data-id=\"2a2f330e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d85094f elementor-position-inline-start elementor-mobile-position-inline-start elementor-widget__width-initial elementor-widget-tablet__width-inherit cstm-icnbx elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"3d85094f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M497.36,69.995c-7.532-7.545-19.753-7.558-27.285-0.032L238.582,300.845l-83.522-90.713   c-7.217-7.834-19.419-8.342-27.266-1.126c-7.841,7.217-8.343,19.425-1.126,27.266l97.126,105.481   c3.557,3.866,8.535,6.111,13.784,6.22c0.141,0.006,0.277,0.006,0.412,0.006c5.101,0,10.008-2.026,13.623-5.628L497.322,97.286   C504.873,89.761,504.886,77.54,497.36,69.995z\"><\/path>\t<\/g><\/g><g>\t<g>\t\t<path d=\"M492.703,236.703c-10.658,0-19.296,8.638-19.296,19.297c0,119.883-97.524,217.407-217.407,217.407   c-119.876,0-217.407-97.524-217.407-217.407c0-119.876,97.531-217.407,217.407-217.407c10.658,0,19.297-8.638,19.297-19.296   C275.297,8.638,266.658,0,256,0C114.84,0,0,114.84,0,256c0,141.154,114.84,256,256,256c141.154,0,256-114.846,256-256   C512,245.342,503.362,236.703,492.703,236.703z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tKostenlose Erstberatung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd01bd elementor-widget elementor-widget-text-editor\" data-id=\"7fd01bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tAusf\u00fchrliche Beratung vor Ort ohne Kosten f\u00fcr den Patienten.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16119c1 e-con-full e-flex e-con e-child\" data-id=\"16119c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53aef075 elementor-position-inline-start elementor-mobile-position-inline-start elementor-widget__width-initial elementor-widget-tablet__width-inherit cstm-icnbx elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"53aef075\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M497.36,69.995c-7.532-7.545-19.753-7.558-27.285-0.032L238.582,300.845l-83.522-90.713   c-7.217-7.834-19.419-8.342-27.266-1.126c-7.841,7.217-8.343,19.425-1.126,27.266l97.126,105.481   c3.557,3.866,8.535,6.111,13.784,6.22c0.141,0.006,0.277,0.006,0.412,0.006c5.101,0,10.008-2.026,13.623-5.628L497.322,97.286   C504.873,89.761,504.886,77.54,497.36,69.995z\"><\/path>\t<\/g><\/g><g>\t<g>\t\t<path d=\"M492.703,236.703c-10.658,0-19.296,8.638-19.296,19.297c0,119.883-97.524,217.407-217.407,217.407   c-119.876,0-217.407-97.524-217.407-217.407c0-119.876,97.531-217.407,217.407-217.407c10.658,0,19.297-8.638,19.297-19.296   C275.297,8.638,266.658,0,256,0C114.84,0,0,114.84,0,256c0,141.154,114.84,256,256,256c141.154,0,256-114.846,256-256   C512,245.342,503.362,236.703,492.703,236.703z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSchnelle Terminvergabe\u200b\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bb9c3b elementor-widget elementor-widget-text-editor\" data-id=\"6bb9c3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tKeine langen Wartezeiten f\u00fcr Interessenten.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a31a580 e-con-full e-flex e-con e-child\" data-id=\"3a31a580\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e5d1138 elementor-position-inline-start elementor-mobile-position-inline-start elementor-widget__width-initial elementor-widget-tablet__width-inherit cstm-icnbx elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"3e5d1138\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M497.36,69.995c-7.532-7.545-19.753-7.558-27.285-0.032L238.582,300.845l-83.522-90.713   c-7.217-7.834-19.419-8.342-27.266-1.126c-7.841,7.217-8.343,19.425-1.126,27.266l97.126,105.481   c3.557,3.866,8.535,6.111,13.784,6.22c0.141,0.006,0.277,0.006,0.412,0.006c5.101,0,10.008-2.026,13.623-5.628L497.322,97.286   C504.873,89.761,504.886,77.54,497.36,69.995z\"><\/path>\t<\/g><\/g><g>\t<g>\t\t<path d=\"M492.703,236.703c-10.658,0-19.296,8.638-19.296,19.297c0,119.883-97.524,217.407-217.407,217.407   c-119.876,0-217.407-97.524-217.407-217.407c0-119.876,97.531-217.407,217.407-217.407c10.658,0,19.297-8.638,19.297-19.296   C275.297,8.638,266.658,0,256,0C114.84,0,0,114.84,0,256c0,141.154,114.84,256,256,256c141.154,0,256-114.846,256-256   C512,245.342,503.362,236.703,492.703,236.703z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMassenabfertigung?  Nicht hier\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98eaff6 elementor-widget elementor-widget-text-editor\" data-id=\"98eaff6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tIndividuelle Behandlung und Beratung durch die Chef\u00e4rztin.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78abaaeb elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"78abaaeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ihre Vorz\u00fcge unserer Privatklinik - \nunsere 5-Sterne-Qualit\u00e4t f\u00fcr ICL-Linsen<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43ba2a65 e-con-full e-flex e-con e-child\" data-id=\"43ba2a65\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-540b22ac e-con-full e-flex e-con e-child\" data-id=\"540b22ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2428f0e6 star-button elementor-widget elementor-widget-heading\" data-id=\"2428f0e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Sicherheit <span style=\"color: #094595\"> \u2605\u2605\u2605\u2605\u2605<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fbbfa0e elementor-widget elementor-widget-text-editor\" data-id=\"2fbbfa0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"165\" data-end=\"517\">Unsere zertifizierten OP-Standards, moderne Technik und streng kontrollierte Hygienema\u00dfnahmen sorgen f\u00fcr h\u00f6chste Sicherheit bei Ihrer <strong>ICL-Implantation<\/strong>. Dank langj\u00e4hriger Erfahrung mit Linsenverfahren garantieren wir eine schonende Behandlung auf h\u00f6chstem medizinischem Niveau \u2013 Ihr Wohlbefinden und Ihre Augengesundheit stehen bei uns an erster Stelle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2b2b465f e-con-full e-flex e-con e-child\" data-id=\"2b2b465f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e1c56 star-button elementor-widget elementor-widget-heading\" data-id=\"4e1c56\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Individuelle Beratung <span style=\"color: #094595\"> \u2605\u2605\u2605\u2605\u2605<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d9907e7 elementor-widget elementor-widget-text-editor\" data-id=\"6d9907e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"561\" data-end=\"886\">Ob hohe Kurzsichtigkeit, d\u00fcnne Hornhaut oder trockene Augen \u2013 wir nehmen uns Zeit, um gemeinsam mit Ihnen zu pr\u00fcfen, ob die <strong>ICL<\/strong> f\u00fcr Sie die passende L\u00f6sung ist. In einem ausf\u00fchrlichen Beratungsgespr\u00e4ch gehen unsere Expert*innen auf Ihre W\u00fcnsche und Voraussetzungen ein und entwickeln ein ma\u00dfgeschneidertes Behandlungskonzept.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a1b178d e-con-full e-flex e-con e-child\" data-id=\"7a1b178d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-203f532b star-button elementor-widget elementor-widget-heading\" data-id=\"203f532b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Qualit\u00e4t <span style=\"color: #094595\"> \u2605\u2605\u2605\u2605\u2605<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c57eaf1 elementor-widget elementor-widget-text-editor\" data-id=\"7c57eaf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"917\" data-end=\"1186\">Mit hochwertigem Collamer-Material, pr\u00e4ziser Linsenfertigung und individuell angepasster Implantation steht die <strong>ICL<\/strong> f\u00fcr exzellente optische Ergebnisse. Wir vertrauen auf bew\u00e4hrte Methoden und modernste Diagnostik \u2013 f\u00fcr langanhaltende Sehqualit\u00e4t, ganz ohne Kompromisse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45c5d4ba e-con-full e-flex e-con e-child\" data-id=\"45c5d4ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29d8958e star-button elementor-widget elementor-widget-heading\" data-id=\"29d8958e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Kompetenz <span style=\"color: #094595\"> \u2605\u2605\u2605\u2605\u2605<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22525b80 elementor-widget elementor-widget-text-editor\" data-id=\"22525b80\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"1218\" data-end=\"1530\">Als erfahrene Privatpraxis f\u00fcr refraktive Linsenimplantation ist das LZW auf Eingriffe mit der <strong>ICL<\/strong> spezialisiert. Von der detaillierten Vermessung bis zur fein abgestimmten Nachsorge begleitet Sie unser Team mit h\u00f6chster Fachkompetenz und pers\u00f6nlichem Engagement \u2013 f\u00fcr Ihre klare Sicht und Ihre Sicherheit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-799784a7 e-flex e-con-boxed e-con e-parent\" data-id=\"799784a7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7d988dcb e-con-full e-flex e-con e-child\" data-id=\"7d988dcb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79ab1dbb elementor-widget elementor-widget-heading\" data-id=\"79ab1dbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">F\u00fcr wen sind die ICL geeignet?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73d5405a elementor-widget elementor-widget-text-editor\" data-id=\"73d5405a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>hoher Fehlsichtigkeit (z.\u202fB. &gt; -8 dpt oder +4 dpt)<\/li><li>zu d\u00fcnner oder irregul\u00e4rer Hornhaut<\/li><li>trockenen Augen, die Laser-Eingriffe erschweren<\/li><li>wunsch nach reversibler, gewebeerhaltender L\u00f6sung<\/li><li>erh\u00f6hter Anspruch an Nacht- und Kontrastsehen<\/li><\/ul><p>LASIK Eignungscheck! Bin ich geeignet?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3cdbe8 elementor-widget-tablet__width-auto elementor-widget__width-initial elementor-widget elementor-widget-shortcode\" data-id=\"b3cdbe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"drflex-button-wrapper\">\n        <a href=\"javascript:toggleDrFlexAppointments()\">\n            <div class=\"drflex-button drflex-button-primary\"\n                style=\"border-radius: 1em;\n                    background-color: #68e697;\n                    color: #ffffff;\n                    padding: 1em;\">ICL Eignungscheck! Bin ich geeignet?\n            <\/div>\n        <\/a>\n    <\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22ec9bbb e-con-full e-flex e-con e-child\" data-id=\"22ec9bbb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2daf91ca elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"2daf91ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t\t            <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-2daf91ca\" data-scroll-on-click=\"no\" data-scroll-speed=\"300\" data-accordion-id=\"2daf91ca\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n            <div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"was-ist-eine-icl\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"1\" aria-controls=\"elementor-tab-content-7661\"><p class=\"eael-accordion-tab-title\">Was ist eine ICL?<\/p><span class=\"eael-advanced-accordion-icon-closed\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><span class=\"eael-advanced-accordion-icon-opened\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span><\/div><div id=\"elementor-tab-content-7661\" class=\"eael-accordion-content clearfix\" data-tab=\"1\" aria-labelledby=\"was-ist-eine-icl\"><p>Die ICL ist eine hauchd\u00fcnne, flexible Linse aus biokompatiblem Collamer-Material, die zus\u00e4tzlich zur k\u00f6rpereigenen Linse in das Auge eingesetzt wird. Sie wird zwischen Iris und nat\u00fcrlicher Linse positioniert \u2013 ohne dabei Gewebe zu entfernen. Im Gegensatz zu Laserverfahren bleibt die nat\u00fcrliche Augenstruktur vollst\u00e4ndig erhalten.<\/p><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"welche-sehfehler-kann-die-icl-korrigieren\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"2\" aria-controls=\"elementor-tab-content-7662\"><p class=\"eael-accordion-tab-title\">Welche Sehfehler kann die ICL korrigieren?<\/p><span class=\"eael-advanced-accordion-icon-closed\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><span class=\"eael-advanced-accordion-icon-opened\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span><\/div><div id=\"elementor-tab-content-7662\" class=\"eael-accordion-content clearfix\" data-tab=\"2\" aria-labelledby=\"welche-sehfehler-kann-die-icl-korrigieren\"><ul><li>Kurzsichtigkeit bis -18 Dioptrien<\/li><li>Weitsichtigkeit bis +10 Dioptrien<\/li><li>Hornhautverkr\u00fcmmung bis 6 Dioptrien<\/li><\/ul><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"vorteile-der-icl-auf-einen-blick\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"3\" aria-controls=\"elementor-tab-content-7663\"><p class=\"eael-accordion-tab-title\">Vorteile der ICL auf einen Blick<\/p><span class=\"eael-advanced-accordion-icon-closed\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><span class=\"eael-advanced-accordion-icon-opened\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span><\/div><div id=\"elementor-tab-content-7663\" class=\"eael-accordion-content clearfix\" data-tab=\"3\" aria-labelledby=\"vorteile-der-icl-auf-einen-blick\"><ul><li>Keine Ver\u00e4nderung der Hornhautstruktur \u2013 ideal bei d\u00fcnner Hornhaut<\/li><li>Hochwertige Sehqualit\u00e4t, auch bei starken Sehfehlern<\/li><li>Reversibel: Die Linse kann wieder entfernt oder ausgetauscht werden<\/li><li>F\u00fcr junge Patienten geeignet, deren nat\u00fcrliche Linse flexibel ist<\/li><li>Kein &#8222;trockeneres Auge&#8220; wie nach manchen Laserbehandlungen<\/li><li>Sehr gute Nachtsicht \u2013 durch zentrale \u00d6ffnung bei EVO Visian ICL<\/li><li>Kurzzeitiger, ambulanter Eingriff mit schneller Erholung<\/li><\/ul><\/div>\n\t\t\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9011fa8 e-flex e-con-boxed e-con e-parent\" data-id=\"9011fa8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f372b8 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"0f372b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Augenoperationen:<br>\nSind ICL-Linsen die optimale L\u00f6sung f\u00fcr mich?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81df648 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"81df648\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Sind Sie bereit f\u00fcr klare Sicht \u2013 ganz ohne Brille, Kontaktlinsen oder Laserbehandlung? Entdecken Sie, ob die ICL \u2013 eine implantierbare Linse \u2013 die passende L\u00f6sung f\u00fcr Ihre Augen ist. Besonders geeignet bei starker Fehlsichtigkeit oder wenn Augenlasern nicht m\u00f6glich ist. Finden Sie jetzt heraus, ob Sie f\u00fcr das ICL-Verfahren infrage kommen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fdd633 e-flex e-con-boxed e-con e-child\" data-id=\"4fdd633\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-657042f e-flex e-con-boxed e-con e-child\" data-id=\"657042f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-687554f e-con-full e-flex e-con e-child\" data-id=\"687554f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37344d0 step-form elementor-widget elementor-widget-shortcode\" data-id=\"37344d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><form id=\"forminator-module-2521\" class=\"forminator-custom-form forminator-custom-form-2521\" method=\"post\" data-forminator-render=\"0\" data-uid=\"6a570822d67e6\"><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><\/form><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a15a42 e-con-full e-transform e-flex e-con e-child\" data-id=\"4a15a42\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;,&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd5c5e elementor-widget elementor-widget-heading\" data-id=\"7fd5c5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">In nur 2 Minuten!<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-230e050f e-flex e-con-boxed e-con e-parent\" data-id=\"230e050f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-62565036 e-con-full e-flex e-con e-child\" data-id=\"62565036\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1361ddff elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"1361ddff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ein Leben lang klare Sicht \u2013 sicher und flexibel mit ICL-Linsen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dd120ae elementor-widget elementor-widget-text-editor\" data-id=\"4dd120ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"391\" data-end=\"1031\">Im LZW setzen wir bei der ICL auf maximale Sicherheit und Flexibilit\u00e4t: Die Linse wird zus\u00e4tzlich zur nat\u00fcrlichen Augenlinse implantiert \u2013 ohne Gewebe zu entfernen. Ein gro\u00dfer Vorteil gegen\u00fcber Laserbehandlungen ist ihre Reversibilit\u00e4t: Die ICL kann bei Bedarf wieder entfernt oder gegen ein anderes Modell getauscht werden. So bleibt Ihre Behandlung anpassbar \u2013 auch bei Ver\u00e4nderungen im Laufe des Lebens.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98c57d4 elementor-widget elementor-widget-button\" data-id=\"98c57d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:0611360220\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Wir helfen pers\u00f6nlich: 0611 - 360 220<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-674e2b4b e-con-full e-flex e-con e-child\" data-id=\"674e2b4b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5819dbd8 elementor-widget elementor-widget-image\" data-id=\"5819dbd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"475\" height=\"594\" src=\"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2026\/04\/1.jpg\" class=\"attachment-full size-full wp-image-8900\" alt=\"\u00c4ltere Frau bei einer pr\u00e4zisen Augenlaserbehandlung im Laserzentrum Wiesbaden.\" srcset=\"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2026\/04\/1.jpg 475w, https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2026\/04\/1-240x300.jpg 240w, https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2026\/04\/1-10x12.jpg 10w\" sizes=\"(max-width: 475px) 100vw, 475px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ee54e24 e-flex e-con-boxed e-con e-parent\" data-id=\"3ee54e24\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-60e38c91 e-con-full e-flex e-con e-child\" data-id=\"60e38c91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-504b763 elementor-widget elementor-widget-heading\" data-id=\"504b763\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fortschrittliche Linsenimplantation (ICL) im LaserZentrum Wiesbaden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1523d2fa elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"1523d2fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t\t            <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-1523d2fa\" data-scroll-on-click=\"no\" data-scroll-speed=\"300\" data-accordion-id=\"1523d2fa\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n            <div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"ausfhrliche-eignungsprfung-und-individuelle-beratung\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"1\" aria-controls=\"elementor-tab-content-3541\"><p class=\"eael-accordion-tab-title\">Ausf\u00fchrliche Eignungspr\u00fcfung und individuelle Beratung<\/p><span class=\"eael-advanced-accordion-icon-closed\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><span class=\"eael-advanced-accordion-icon-opened\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span><\/div><div id=\"elementor-tab-content-3541\" class=\"eael-accordion-content clearfix\" data-tab=\"1\" aria-labelledby=\"ausfhrliche-eignungsprfung-und-individuelle-beratung\"><p class=\"\">Zu Beginn f\u00fchren wir eine umfassende Voruntersuchung durch. Dabei messen wir u.\u202fa. Ihre Sehst\u00e4rke, Hornhautdicke, Pupillengr\u00f6\u00dfe und die Tiefe der vorderen Augenkammer \u2013 essenzielle Werte f\u00fcr die Auswahl und Platzierung der ICL. Anhand dieser Daten pr\u00fcfen wir, ob die anatomischen Voraussetzungen f\u00fcr eine Implantation erf\u00fcllt sind. In einem pers\u00f6nlichen Gespr\u00e4ch kl\u00e4ren wir zudem Ihre Erwartungen, beantworten alle offenen Fragen und entwickeln gemeinsam einen individuellen Behandlungsplan.<\/p><p class=\"\">\u00a0<\/p><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"der-eingriff-sicher-schonend-ambulant\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"2\" aria-controls=\"elementor-tab-content-3542\"><p class=\"eael-accordion-tab-title\">Der Eingriff \u2013 sicher, schonend, ambulant<\/p><span class=\"eael-advanced-accordion-icon-closed\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><span class=\"eael-advanced-accordion-icon-opened\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span><\/div><div id=\"elementor-tab-content-3542\" class=\"eael-accordion-content clearfix\" data-tab=\"2\" aria-labelledby=\"der-eingriff-sicher-schonend-ambulant\"><p class=\"\">Am Tag der Operation erhalten Sie eine lokale Bet\u00e4ubung mittels Augentropfen. Die eigentliche Implantation dauert etwa 10\u201315 Minuten pro Auge. Durch einen winzigen Schnitt am Hornhautrand wird die ICL gefaltet in das Auge eingebracht, wo sie sich selbst entfaltet und sanft zwischen Iris und nat\u00fcrlicher Linse positioniert. Der Eingriff ist in der Regel schmerzfrei, die Hornhaut bleibt nahezu unber\u00fchrt \u2013 ein gro\u00dfer Vorteil gegen\u00fcber Laserverfahren.<\/p><p class=\"\">\u00a0<\/p><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"nachkontrollen-und-anpassungsphase\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"3\" aria-controls=\"elementor-tab-content-3543\"><p class=\"eael-accordion-tab-title\">Nachkontrollen und Anpassungsphase<\/p><span class=\"eael-advanced-accordion-icon-closed\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><span class=\"eael-advanced-accordion-icon-opened\"><svg aria-hidden=\"true\" class=\"fa-accordion-icon e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span><\/div><div id=\"elementor-tab-content-3543\" class=\"eael-accordion-content clearfix\" data-tab=\"3\" aria-labelledby=\"nachkontrollen-und-anpassungsphase\"><p class=\"\">Bereits am Tag nach dem Eingriff berichten viele Patienten von einer deutlich verbesserten Sehleistung. In den folgenden Wochen f\u00fchren wir engmaschige Kontrollen durch, um den Sitz der Linse, den Augeninnendruck und die Stabilit\u00e4t Ihrer Sehsch\u00e4rfe zu \u00fcberwachen. Die Heilungsphase ist meist kurz \u2013 viele kehren schon nach wenigen Tagen in den Alltag zur\u00fcck.<\/p><\/div>\n\t\t\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc5a978 elementor-widget elementor-widget-button\" data-id=\"dc5a978\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:info@lzw-wiesbaden.de\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Noch Fragen? Jetzt Kontaktieren!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-643d63bd e-flex e-con-boxed e-con e-parent\" data-id=\"643d63bd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-70a56368 e-con-full e-flex e-con e-child\" data-id=\"70a56368\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50a5acd8 elementor-widget elementor-widget-heading\" data-id=\"50a5acd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Endlich brillenfrei \u2013 das sagen unsere gl\u00fccklichen Patienten<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7518ed85 elementor-widget elementor-widget-text-editor\" data-id=\"7518ed85\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Basierend auf authentischen Erfahrungen und herausragenden Ergebnissen sind wir stolz darauf, die bestbewertete Augenlaserklinik in Wiesbaden zu sein. Unsere <strong>4,8 Sterne bei Google<\/strong> Bewertungen sprechen hierbei f\u00fcr sich. Gemeinsam begleiten wir Sie, Schritt f\u00fcr Schritt, auf dem Weg zu einem Leben ohne Brille.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13aac3c7 e-con-full e-flex e-con e-child\" data-id=\"13aac3c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3dfdfac5 elementor-testimonial--layout-image_above review-rating elementor-testimonial--skin-default elementor-testimonial--align-center elementor-arrows-yes elementor-widget elementor-widget-testimonial-carousel\" data-id=\"3dfdfac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<span class=\"rating\" style=\"color: #094595\"> \u2605\u2605\u2605\u2605\u2605<\/span><\/br><\/br>\nSehr kompetentes, gut organiertes Team und \u00c4rzte. Super freundlich. Hoffentlich keine neuen Linsen mehr. Wenn aber doch dann nur im LZW. Habe Trifokallinsen bekommen\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Andreas Harth, April 2021<\/span><span class=\"elementor-testimonial__title\">via Google<\/span><\/cite>\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2023\/12\/lzw_chefaerztin_gespraech__wiesbaden.jpg\" alt=\"Andreas Harth, April 2021\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<span class=\"rating\" style=\"color: #094595\"> \u2605\u2605\u2605\u2605\u2605<\/span><\/br><\/br>Super Job von Frau Dr. Steinhorst und ihrem Team! Sehr schnelle Terminvergabe! Erstuntersuchung und Op-Termin innerhalb von wenigen Tagen. Durch das detailierte Aufkl\u00e4rungsgespr\u00e4ch f\u00fchlte ich mich sehr gut betreut und sicher. Die OP selbst verlief ohne Komplikationen, war komplett schmerzlos und \u00fcberraschend schnell. Kann ich jedem, der brillenfrei werden m\u00f6chte, nur empfehlen!\t\t\t\t\t<\/div>\n\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Lennart J\u00e4ger, Januar 2021<\/span><span class=\"elementor-testimonial__title\">via Google<\/span><\/cite>\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2023\/12\/lzw_chefaerztin_gespraech__wiesbaden.jpg\" alt=\"Lennart J\u00e4ger, Januar 2021\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<span class=\"rating\" style=\"color: #094595\"> \u2605\u2605\u2605\u2605\u2605<\/span><\/br><\/br>\nSuper unkomplizierte Durchf\u00fchrung! Sehr freundliches Personal, das auf alle Fragen detailliert eingegangen ist.\t\t\t\t\t<\/div>\n\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Patrick Lieser, Januar 2024<\/span><span class=\"elementor-testimonial__title\">via Google<\/span><\/cite>\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2023\/12\/lzw_chefaerztin_gespraech__wiesbaden.jpg\" alt=\"Patrick Lieser, Januar 2024\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<span class=\"rating\" style=\"color: #094595\"> \u2605\u2605\u2605\u2605\u2605<\/span><\/br><\/br> Netter Umgang, geduldiges Personal, fachlich auch super, sehr zu empfehlen. bin immer wieder gerne zur Kontrolle dort. (Zuerst Laserbehandlung, Jahre sp\u00e4ter dann Linsentausch)\t\t\t\t\t<\/div>\n\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Js Dn, November 2023<\/span><span class=\"elementor-testimonial__title\">via Google<\/span><\/cite>\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2023\/12\/lzw_chefaerztin_gespraech__wiesbaden.jpg\" alt=\"Js Dn, November 2023\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Voriger\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ad83e4 e-flex e-con-boxed e-con e-parent\" data-id=\"1ad83e4\" data-element_type=\"container\" data-e-type=\"container\" id=\"form-id\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fdfcb25 elementor-widget elementor-widget-heading\" data-id=\"5fdfcb25\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Jetzt ein individuelles Erstgespr\u00e4ch anfragen:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c40481 elementor-widget elementor-widget-wpforms\" data-id=\"1c40481\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container \" id=\"wpforms-44\"><form id=\"wpforms-form-44\" class=\"wpforms-validate wpforms-form\" data-formid=\"44\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/7594\" data-token=\"78d8e8b6b29d1c5164513c8ebfbdde7e\" data-token-time=\"1784088610\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\">\t\t<div id=\"wpforms-44-field_3-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"3\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-44-field_3\" >Informationen Telefonnummer Datenschutz<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-44-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-44-field_8-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"8\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-44-field_8\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-44-field_8\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][8]\" placeholder=\"Vor- und Nachname\" required><\/div><div id=\"wpforms-44-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-44-field_1\">Email-Adresse <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-44-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"E-Mail Adresse\" spellcheck=\"false\" required><\/div><div id=\"wpforms-44-field_11-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"11\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-44-field_11\">Telefonnummer<\/label><input type=\"number\" id=\"wpforms-44-field_11\" class=\"wpforms-field-large\" name=\"wpforms[fields][11]\" placeholder=\"Telefonnummer\" step=\"any\" ><\/div><div id=\"wpforms-44-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-44-field_2\">Nachricht <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-44-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Nachricht\" required><\/textarea><\/div><div id=\"wpforms-44-field_9-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"9\"><label class=\"wpforms-field-label\">Weitere Informationen<\/label><ul id=\"wpforms-44-field_9\"><li class=\"choice-1 depth-1 wpforms-selected\"><input type=\"checkbox\" id=\"wpforms-44-field_9_1\" name=\"wpforms[fields][9][]\" value=\"Ich bitte um einen R\u00fcckruf.\"   checked='checked'><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_9_1\">Ich bitte um einen R\u00fcckruf.<\/label><\/li><\/ul><\/div><div id=\"wpforms-44-field_5-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"5\"><label class=\"wpforms-field-label\">Datenschutz <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-44-field_5\" class=\"wpforms-field-required\"><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-44-field_5_2\" name=\"wpforms[fields][5][]\" value=\"Hiermit erkl\u00e4re ich mich mit der Verwendung meiner pers\u00f6nlichen Daten entsprechend der Datenschutzinformation einverstanden.\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-44-field_5_2\">Hiermit erkl\u00e4re ich mich mit der Verwendung meiner pers\u00f6nlichen Daten entsprechend der Datenschutzinformation einverstanden.<\/label><\/li><\/ul><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-44-field_3-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-44-field_3-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-44-field_3-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"44\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/lzw-wiesbaden.de\/en\/wp-json\/wp\/v2\/pages\/7594\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-44\" class=\"wpforms-submit\" data-alt-text=\"Anfrage wird gesendet...\" data-submit-text=\"Abschicken\" aria-live=\"assertive\" value=\"wpforms-submit\">Abschicken<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ICL-Linsen ab 2.000\u20ac\/Auge Implantierbare Kontaktlinsen (ICL &amp; IPCL) Die ICL-Linse ist besonders dann sinnvoll, wenn klassische Verfahren wie LASIK oder PRK nicht angewendet werden k\u00f6nnen \u2013 zum Beispiel bei hoher Fehlsichtigkeit, d\u00fcnner Hornhaut oder trockenen Augen. Termin vereinbaren: 0611-360 220 Kostenlose Erstberatung Ausf\u00fchrliche Beratung vor Ort ohne Kosten f\u00fcr den Patienten. Schnelle Terminvergabe\u200b Keine langen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4585,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-7594","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ICL-Linsen - Laserzentrum Wiesbaden<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ICL-Linsen - Laserzentrum Wiesbaden\" \/>\n<meta property=\"og:description\" content=\"ICL-Linsen ab 2.000\u20ac\/Auge Implantierbare Kontaktlinsen (ICL &amp; IPCL) Die ICL-Linse ist besonders dann sinnvoll, wenn klassische Verfahren wie LASIK oder PRK nicht angewendet werden k\u00f6nnen \u2013 zum Beispiel bei hoher Fehlsichtigkeit, d\u00fcnner Hornhaut oder trockenen Augen. Termin vereinbaren: 0611-360 220 Kostenlose Erstberatung Ausf\u00fchrliche Beratung vor Ort ohne Kosten f\u00fcr den Patienten. Schnelle Terminvergabe\u200b Keine langen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lzw-wiesbaden.de\/en\/lens-surgery\/icl-linsen\/\" \/>\n<meta property=\"og:site_name\" content=\"Laserzentrum Wiesbaden\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-23T00:21:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2026\/04\/1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/en\\\/lens-surgery\\\/icl-linsen\\\/\",\"url\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/en\\\/lens-surgery\\\/icl-linsen\\\/\",\"name\":\"ICL-Linsen - Laserzentrum Wiesbaden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/en\\\/lens-surgery\\\/icl-linsen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/en\\\/lens-surgery\\\/icl-linsen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1.jpg\",\"datePublished\":\"2025-04-07T07:57:58+00:00\",\"dateModified\":\"2026-05-23T00:21:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/en\\\/lens-surgery\\\/icl-linsen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lzw-wiesbaden.de\\\/en\\\/lens-surgery\\\/icl-linsen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/en\\\/lens-surgery\\\/icl-linsen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1.jpg\",\"contentUrl\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/en\\\/lens-surgery\\\/icl-linsen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Linsenoperation\",\"item\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/linsenoperation\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ICL-Linsen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/#website\",\"url\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/\",\"name\":\"Laserzentrum Wiesbaden\",\"description\":\"Privatklinik f\u00fcr Sehkorrekturen\",\"publisher\":{\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/#organization\",\"name\":\"Laserzentrum Wiesbaden\",\"url\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/lzw_logo_schriftzug.png\",\"contentUrl\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/lzw_logo_schriftzug.png\",\"width\":600,\"height\":72,\"caption\":\"Laserzentrum Wiesbaden\"},\"image\":{\"@id\":\"https:\\\/\\\/lzw-wiesbaden.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ICL-Linsen - Laserzentrum Wiesbaden","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"ICL-Linsen - Laserzentrum Wiesbaden","og_description":"ICL-Linsen ab 2.000\u20ac\/Auge Implantierbare Kontaktlinsen (ICL &amp; IPCL) Die ICL-Linse ist besonders dann sinnvoll, wenn klassische Verfahren wie LASIK oder PRK nicht angewendet werden k\u00f6nnen \u2013 zum Beispiel bei hoher Fehlsichtigkeit, d\u00fcnner Hornhaut oder trockenen Augen. Termin vereinbaren: 0611-360 220 Kostenlose Erstberatung Ausf\u00fchrliche Beratung vor Ort ohne Kosten f\u00fcr den Patienten. Schnelle Terminvergabe\u200b Keine langen [&hellip;]","og_url":"https:\/\/lzw-wiesbaden.de\/en\/lens-surgery\/icl-linsen\/","og_site_name":"Laserzentrum Wiesbaden","article_modified_time":"2026-05-23T00:21:23+00:00","og_image":[{"url":"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2026\/04\/1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lzw-wiesbaden.de\/en\/lens-surgery\/icl-linsen\/","url":"https:\/\/lzw-wiesbaden.de\/en\/lens-surgery\/icl-linsen\/","name":"ICL-Linsen - Laserzentrum Wiesbaden","isPartOf":{"@id":"https:\/\/lzw-wiesbaden.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lzw-wiesbaden.de\/en\/lens-surgery\/icl-linsen\/#primaryimage"},"image":{"@id":"https:\/\/lzw-wiesbaden.de\/en\/lens-surgery\/icl-linsen\/#primaryimage"},"thumbnailUrl":"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2026\/04\/1.jpg","datePublished":"2025-04-07T07:57:58+00:00","dateModified":"2026-05-23T00:21:23+00:00","breadcrumb":{"@id":"https:\/\/lzw-wiesbaden.de\/en\/lens-surgery\/icl-linsen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lzw-wiesbaden.de\/en\/lens-surgery\/icl-linsen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lzw-wiesbaden.de\/en\/lens-surgery\/icl-linsen\/#primaryimage","url":"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2026\/04\/1.jpg","contentUrl":"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2026\/04\/1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/lzw-wiesbaden.de\/en\/lens-surgery\/icl-linsen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/lzw-wiesbaden.de\/"},{"@type":"ListItem","position":2,"name":"Linsenoperation","item":"https:\/\/lzw-wiesbaden.de\/linsenoperation\/"},{"@type":"ListItem","position":3,"name":"ICL-Linsen"}]},{"@type":"WebSite","@id":"https:\/\/lzw-wiesbaden.de\/#website","url":"https:\/\/lzw-wiesbaden.de\/","name":"Laserzentrum Wiesbaden","description":"private clinic for vision correction","publisher":{"@id":"https:\/\/lzw-wiesbaden.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lzw-wiesbaden.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lzw-wiesbaden.de\/#organization","name":"Laserzentrum Wiesbaden","url":"https:\/\/lzw-wiesbaden.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lzw-wiesbaden.de\/#\/schema\/logo\/image\/","url":"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2023\/12\/lzw_logo_schriftzug.png","contentUrl":"https:\/\/lzw-wiesbaden.de\/wp-content\/uploads\/2023\/12\/lzw_logo_schriftzug.png","width":600,"height":72,"caption":"Laserzentrum Wiesbaden"},"image":{"@id":"https:\/\/lzw-wiesbaden.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lzw-wiesbaden.de\/en\/wp-json\/wp\/v2\/pages\/7594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lzw-wiesbaden.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lzw-wiesbaden.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lzw-wiesbaden.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lzw-wiesbaden.de\/en\/wp-json\/wp\/v2\/comments?post=7594"}],"version-history":[{"count":66,"href":"https:\/\/lzw-wiesbaden.de\/en\/wp-json\/wp\/v2\/pages\/7594\/revisions"}],"predecessor-version":[{"id":9562,"href":"https:\/\/lzw-wiesbaden.de\/en\/wp-json\/wp\/v2\/pages\/7594\/revisions\/9562"}],"up":[{"embeddable":true,"href":"https:\/\/lzw-wiesbaden.de\/en\/wp-json\/wp\/v2\/pages\/4585"}],"wp:attachment":[{"href":"https:\/\/lzw-wiesbaden.de\/en\/wp-json\/wp\/v2\/media?parent=7594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}